{"id":4104,"date":"2025-02-11T13:07:13","date_gmt":"2025-02-11T18:07:13","guid":{"rendered":"https:\/\/www.laroutedesvins.ca\/entreprises-accessibles\/"},"modified":"2025-06-02T10:11:06","modified_gmt":"2025-06-02T14:11:06","slug":"accessible-companies","status":"publish","type":"page","link":"https:\/\/www.laroutedesvins.ca\/en\/accessible-companies\/","title":{"rendered":"Accessible companies"},"content":{"rendered":"<style>.kb-row-layout-id4104_803260-03 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4104_803260-03 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4104_803260-03 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-lg, 4rem);max-width:var( --global-content-width, 1600px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, calc(50% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)))minmax(0, calc(50% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)));}.kb-row-layout-id4104_803260-03 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4104_803260-03 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id4104_803260-03 > .kt-row-column-wrap{row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}}<\/style><section class=\"kb-row-layout-wrap kb-row-layout-id4104_803260-03 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4104_f69c77-ff > .kt-inside-inner-col,.kadence-column4104_f69c77-ff > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4104_f69c77-ff > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4104_f69c77-ff > .kt-inside-inner-col{flex-direction:column;}.kadence-column4104_f69c77-ff > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4104_f69c77-ff > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4104_f69c77-ff{position:relative;}@media all and (max-width: 1024px){.kadence-column4104_f69c77-ff > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4104_f69c77-ff > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4104_f69c77-ff\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading\">Companies that promote accessibility for an inclusive experience<\/h2>\n\n\n\n<p>Several Brome-Missisquoi companies have put in place measures to meet the specific needs of people with disabilities.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns4104_47ae5c-4e{padding-bottom:var(--global-kb-spacing-lg, 3rem);gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns4104_47ae5c-4e .kt-button{font-weight:normal;font-style:normal;}.kt-btns4104_47ae5c-4e .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns4104_47ae5c-4e .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns4104_47ae5c-4e .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns4104_47ae5c-4e .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns4104_47ae5c-4e .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns4104_47ae5c-4e .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns4104_47ae5c-4e .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns4104_47ae5c-4e\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn4104_190f7d-4c.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn4104_190f7d-4c.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);}.kb-btn4104_190f7d-4c.kb-button .kb-svg-icon-wrap{color:var(--global-palette7, #EDF2F7);font-size:30px;--kb-button-icon-size:30px;}.wp-block-kadence-advancedbtn .kb-btn4104_190f7d-4c.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn4104_190f7d-4c.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette3, #1A202C);}<\/style><a class=\"kb-button kt-button button kb-btn4104_190f7d-4c kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-true  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/www.laroutedesvins.ca\/attraits\/?filter%5B%5D=Entreprises%20accessibles\"><span class=\"kb-svg-icon-wrap kb-svg-icon-icon-carte kt-btn-icon-side-left\"><svg viewBox=\"0 0 1024 1024\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M405.333 426.667c29.867 29.867 68.267 46.933 110.933 46.933s81.067-17.067 110.933-46.933c29.867-29.867 46.933-68.267 46.933-110.933s-17.067-81.067-46.933-110.933c-29.867-29.867-68.267-46.933-110.933-46.933s-81.067 17.067-110.933 46.933c-29.867 29.867-46.933 68.267-46.933 110.933s12.8 76.8 46.933 110.933zM516.267 213.333c29.867 0 55.467 12.8 76.8 29.867 21.333 21.333 29.867 46.933 29.867 76.8s-12.8 55.467-29.867 76.8c-21.333 21.333-46.933 29.867-76.8 29.867s-51.2-8.533-76.8-29.867c-21.333-21.333-29.867-46.933-29.867-76.8s12.8-55.467 29.867-76.8c21.333-21.333 46.933-29.867 76.8-29.867z\"\/><path d=\"M891.733 874.667l-119.467-307.2c0-8.533-12.8-17.067-21.333-17.067h-81.067c17.067-21.333 29.867-42.667 42.667-68.267 29.867-59.733 38.4-106.667 38.4-166.4 0-64-25.6-119.467-68.267-166.4-42.667-42.667-102.4-68.267-166.4-68.267s-119.467 25.6-166.4 68.267-68.267 102.4-68.267 166.4c0 59.733 8.533 110.933 38.4 166.4 12.8 21.333 25.6 42.667 42.667 68.267h-81.067c-8.533 0-17.067 4.267-21.333 17.067l-119.467 302.933c0 8.533 0 17.067 0 21.333 4.267 8.533 12.8 12.8 21.333 12.8h708.267c0 0 4.267 0 8.533 0 12.8-4.267 17.067-17.067 12.8-29.867zM614.4 857.6l183.467-93.867 38.4 93.867h-221.867zM516.267 132.267c51.2 0 98.133 21.333 132.267 55.467s51.2 72.533 55.467 132.267c0 51.2-8.533 93.867-34.133 145.067-12.8 25.6-29.867 46.933-46.933 68.267-8.533 8.533-17.067 21.333-21.333 29.867-25.6 25.6-51.2 55.467-85.333 85.333-8.533-8.533-17.067-17.067-25.6-25.6s-17.067-21.333-29.867-29.867c-8.533-12.8-21.333-21.333-29.867-34.133-29.867-34.133-51.2-64-68.267-98.133-21.333-38.4-38.4-98.133-34.133-145.067 0-51.2 21.333-98.133 55.467-132.267s81.067-55.467 132.267-55.467zM469.333 669.867c8.533 8.533 21.333 21.333 29.867 29.867s21.333 8.533 29.867 0c38.4-34.133 72.533-64 98.133-98.133h106.667l46.933 119.467-264.533 136.533-179.2-115.2 128-68.267zM401.067 601.6c8.533 12.8 21.333 21.333 29.867 34.133l-187.733 102.4 51.2-132.267h106.667zM217.6 802.133l72.533-38.4 145.067 93.867h-238.933l21.333-55.467z\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Accessible companies<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn4104_b1412d-13.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn4104_b1412d-13.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);}.kb-btn4104_b1412d-13.kb-button .kb-svg-icon-wrap{color:var(--global-palette7, #EDF2F7);font-size:30px;--kb-button-icon-size:30px;}.wp-block-kadence-advancedbtn .kb-btn4104_b1412d-13.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn4104_b1412d-13.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette3, #1A202C);}<\/style><a class=\"kb-button kt-button button kb-btn4104_b1412d-13 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-true  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/www.laroutedesvins.ca\/attraits\/?filter%5B%5D=Entreprises%20partiellement%20accessibles\"><span class=\"kb-svg-icon-wrap kb-svg-icon-icon-carte kt-btn-icon-side-left\"><svg viewBox=\"0 0 1024 1024\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M405.333 426.667c29.867 29.867 68.267 46.933 110.933 46.933s81.067-17.067 110.933-46.933c29.867-29.867 46.933-68.267 46.933-110.933s-17.067-81.067-46.933-110.933c-29.867-29.867-68.267-46.933-110.933-46.933s-81.067 17.067-110.933 46.933c-29.867 29.867-46.933 68.267-46.933 110.933s12.8 76.8 46.933 110.933zM516.267 213.333c29.867 0 55.467 12.8 76.8 29.867 21.333 21.333 29.867 46.933 29.867 76.8s-12.8 55.467-29.867 76.8c-21.333 21.333-46.933 29.867-76.8 29.867s-51.2-8.533-76.8-29.867c-21.333-21.333-29.867-46.933-29.867-76.8s12.8-55.467 29.867-76.8c21.333-21.333 46.933-29.867 76.8-29.867z\"\/><path d=\"M891.733 874.667l-119.467-307.2c0-8.533-12.8-17.067-21.333-17.067h-81.067c17.067-21.333 29.867-42.667 42.667-68.267 29.867-59.733 38.4-106.667 38.4-166.4 0-64-25.6-119.467-68.267-166.4-42.667-42.667-102.4-68.267-166.4-68.267s-119.467 25.6-166.4 68.267-68.267 102.4-68.267 166.4c0 59.733 8.533 110.933 38.4 166.4 12.8 21.333 25.6 42.667 42.667 68.267h-81.067c-8.533 0-17.067 4.267-21.333 17.067l-119.467 302.933c0 8.533 0 17.067 0 21.333 4.267 8.533 12.8 12.8 21.333 12.8h708.267c0 0 4.267 0 8.533 0 12.8-4.267 17.067-17.067 12.8-29.867zM614.4 857.6l183.467-93.867 38.4 93.867h-221.867zM516.267 132.267c51.2 0 98.133 21.333 132.267 55.467s51.2 72.533 55.467 132.267c0 51.2-8.533 93.867-34.133 145.067-12.8 25.6-29.867 46.933-46.933 68.267-8.533 8.533-17.067 21.333-21.333 29.867-25.6 25.6-51.2 55.467-85.333 85.333-8.533-8.533-17.067-17.067-25.6-25.6s-17.067-21.333-29.867-29.867c-8.533-12.8-21.333-21.333-29.867-34.133-29.867-34.133-51.2-64-68.267-98.133-21.333-38.4-38.4-98.133-34.133-145.067 0-51.2 21.333-98.133 55.467-132.267s81.067-55.467 132.267-55.467zM469.333 669.867c8.533 8.533 21.333 21.333 29.867 29.867s21.333 8.533 29.867 0c38.4-34.133 72.533-64 98.133-98.133h106.667l46.933 119.467-264.533 136.533-179.2-115.2 128-68.267zM401.067 601.6c8.533 12.8 21.333 21.333 29.867 34.133l-187.733 102.4 51.2-132.267h106.667zM217.6 802.133l72.533-38.4 145.067 93.867h-238.933l21.333-55.467z\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Partially accessible companies <\/span><\/a><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4104_02508c-4c, .wp-block-kadence-advancedheading.kt-adv-heading4104_02508c-4c[data-kb-block=\"kb-adv-heading4104_02508c-4c\"]{margin-bottom:var(--global-kb-spacing-sm, 1.5rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4104_02508c-4c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4104_02508c-4c[data-kb-block=\"kb-adv-heading4104_02508c-4c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4104_02508c-4c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4104_02508c-4c[data-kb-block=\"kb-adv-heading4104_02508c-4c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading4104_02508c-4c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4104_02508c-4c\">Accessible companies<\/h3>\n\n\n<div id=\"shortcode-multiple-attractions-all\" class=\"attraits shortcode-multiple-attractions grid-1\"><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4104_f8a439-7a, .wp-block-kadence-advancedheading.kt-adv-heading4104_f8a439-7a[data-kb-block=\"kb-adv-heading4104_f8a439-7a\"]{margin-bottom:var(--global-kb-spacing-sm, 1.5rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4104_f8a439-7a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4104_f8a439-7a[data-kb-block=\"kb-adv-heading4104_f8a439-7a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4104_f8a439-7a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4104_f8a439-7a[data-kb-block=\"kb-adv-heading4104_f8a439-7a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading4104_f8a439-7a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4104_f8a439-7a\">Partially accessible companies<\/h3>\n\n\n<div id=\"shortcode-multiple-attractions-all\" class=\"attraits shortcode-multiple-attractions grid-1\"><\/div>\n<\/div><\/div>\n\n\n<style>#wrapper.site{overflow:clip;}.kadence-column4104_4b14a6-3e > .kt-inside-inner-col,.kadence-column4104_4b14a6-3e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4104_4b14a6-3e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4104_4b14a6-3e > .kt-inside-inner-col{flex-direction:column;}.kadence-column4104_4b14a6-3e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4104_4b14a6-3e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4104_4b14a6-3e{position:relative;}@media all and (max-width: 1024px){.kadence-column4104_4b14a6-3e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4104_4b14a6-3e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4104_4b14a6-3e kb-section-is-sticky\"><div class=\"kt-inside-inner-col\"><style>.kb-image4104_7d4fd2-f7 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-right-radius:12px;border-bottom-left-radius:12px;}.kb-image4104_7d4fd2-f7 img.kb-img, .kb-image4104_7d4fd2-f7 .kb-img img{border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-right-radius:12px;border-bottom-left-radius:12px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4104_7d4fd2-f7 size-full\"><img decoding=\"async\" width=\"760\" height=\"950\" src=\"https:\/\/www.laroutedesvins.ca\/wp-content\/uploads\/2025\/03\/Accessible.webp\" alt=\"\" class=\"kb-img wp-image-3806\" title=\"\"><\/figure>\n<\/div><\/div>\n\n<\/div><\/section>","protected":false},"excerpt":{"rendered":"<p>Companies that promote accessibility for an inclusive experience Several Brome-Missisquoi companies have put in place measures to meet the specific needs of people with disabilities. Accessible companies Partially accessible companies<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-4104","page","type-page","status-publish","hentry"],"acf":[],"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"jfares","author_link":"https:\/\/www.laroutedesvins.ca\/en\/author\/jfares\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/www.laroutedesvins.ca\/en\/wp-json\/wp\/v2\/pages\/4104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laroutedesvins.ca\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.laroutedesvins.ca\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.laroutedesvins.ca\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laroutedesvins.ca\/en\/wp-json\/wp\/v2\/comments?post=4104"}],"version-history":[{"count":2,"href":"https:\/\/www.laroutedesvins.ca\/en\/wp-json\/wp\/v2\/pages\/4104\/revisions"}],"predecessor-version":[{"id":4714,"href":"https:\/\/www.laroutedesvins.ca\/en\/wp-json\/wp\/v2\/pages\/4104\/revisions\/4714"}],"wp:attachment":[{"href":"https:\/\/www.laroutedesvins.ca\/en\/wp-json\/wp\/v2\/media?parent=4104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}